{"id":2034,"date":"2024-04-29T08:01:25","date_gmt":"2024-04-29T13:01:25","guid":{"rendered":"https:\/\/latam.cognita.network\/vermontmedellin-v2\/?page_id=2034"},"modified":"2025-01-31T22:17:32","modified_gmt":"2025-02-01T03:17:32","slug":"familia-cognita-redcol","status":"publish","type":"page","link":"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/","title":{"rendered":"Familia Cognita &#8211; Redcol"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2034\" class=\"elementor elementor-2034\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-435a6549 e-con-full e-flex e-con e-child\" data-id=\"435a6549\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-517ecb6d elementor-widget elementor-widget-image\" data-id=\"517ecb6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/12\/Banner_FAMILIA-COGNITA-REDCOL_Gimnasio-del-Norte.jpg?w=1440\" title=\"Banner_FAMILIA-C\u00d3GNITA-REDCOL_Gimnasio del Norte\" alt=\"Banner_FAMILIA-C\u00d3GNITA-REDCOL_Gimnasio del Norte\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b37496e e-con-full e-flex e-con e-parent\" data-id=\"5b37496e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a7b60f9 elementor-widget elementor-widget-image\" data-id=\"7a7b60f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/11\/welcome.png?w=1440\" title=\"welcome\" alt=\"welcome\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63d8929a e-con-full e-flex e-con e-parent\" data-id=\"63d8929a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-476b294 e-flex e-con-boxed e-con e-child\" data-id=\"476b294\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1a43fb6b e-con-full e-flex e-con e-child\" data-id=\"1a43fb6b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-73862762 e-con-full e-flex e-con e-child\" data-id=\"73862762\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3de5cdc9 elementor-widget elementor-widget-video\" data-id=\"3de5cdc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/k-6YlBhsU9Y&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bc7815 elementor-widget elementor-widget-heading\" data-id=\"1bc7815\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Somos Redcol<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eaf136d elementor-widget elementor-widget-text-editor\" data-id=\"eaf136d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Creemos en el poder transformador de la educaci\u00f3n. En nuestra red de colegios, cada estudiante es \u00fanico, y ofrecemos un servicio de excelencia que respeta, inspira y potencia su desarrollo acad\u00e9mico, social y emocional. Con est\u00e1ndares internacionales y un enfoque hol\u00edstico, preparamos a los j\u00f3venes para liderar el futuro, fortaleciendo nuestra comunidad con innovaci\u00f3n, valores y prop\u00f3sito.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c61e95f e-con-full e-flex e-con e-child\" data-id=\"c61e95f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-082fe79 elementor-widget elementor-widget-video\" data-id=\"082fe79\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=WOPF1SGXPpE&amp;t=6s&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e33b25 elementor-widget elementor-widget-heading\" data-id=\"6e33b25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Somos Cognita<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-819078a elementor-widget elementor-widget-text-editor\" data-id=\"819078a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En Cognita, celebramos la singularidad de cada estudiante y cada colegio. Fomentamos sus talentos individuales y brindamos apoyo acad\u00e9mico, social y emocional, preservando la esencia \u00fanica de cada instituci\u00f3n. Con el respaldo de m\u00e1s de 100 colegios en 17 pa\u00edses, ofrecemos una educaci\u00f3n verdaderamente global que empodera a estudiantes, docentes y comunidades para que prosperen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e089517 button_white e-flex e-con-boxed e-con e-parent\" data-id=\"5e089517\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-46c87de0 e-con-full e-flex e-con e-child\" data-id=\"46c87de0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a0f52dd elementor-widget elementor-widget-heading\" data-id=\"2a0f52dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Educaci\u00f3n hol\u00edstica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e140a1e e-con-full e-flex e-con e-child\" data-id=\"e140a1e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-10d7864f e-con-full e-flex e-con e-child\" data-id=\"10d7864f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-687e776d elementor-widget elementor-widget-image\" data-id=\"687e776d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/12\/Niveles-Academicos_Gimnasio-del-Norte-2.png?w=1080\" title=\"Niveles Acade\u0301micos_Gimnasio del Norte\" alt=\"Niveles Acade\u0301micos_Gimnasio del Norte\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2661d916 elementor-widget elementor-widget-heading\" data-id=\"2661d916\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Excelencia acad\u00e9mica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f4d7719 elementor-widget elementor-widget-text-editor\" data-id=\"7f4d7719\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"mb-2 flex gap-3 empty:hidden -ml-2\"><div class=\"items-center justify-start rounded-xl p-1 z-10 -mt-1 bg-token-main-surface-primary screen-arch:mt-1 md:absolute md:sr-only\">Nuestros colegios son \u00fanicos, pero comparten una caracter\u00edstica: la excelencia. Logramos grandes resultados acad\u00e9micos mientras fomentamos el desarrollo social, emocional y cognitivo mediante pr\u00e1cticas de ense\u00f1anza basadas en evidencia.<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-540517b6 e-con-full e-flex e-con e-child\" data-id=\"540517b6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78357f85 elementor-widget elementor-widget-image\" data-id=\"78357f85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/12\/Niveles-Academicos_Gimnasio-del-Norte-4.png?w=1000\" title=\"Niveles Acade\u0301micos_Gimnasio del Norte\" alt=\"Ni\u00f1o sonriendo en zonas de juegos\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f089bc elementor-widget elementor-widget-heading\" data-id=\"7f089bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bienestar<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f3cf3d2 elementor-widget elementor-widget-text-editor\" data-id=\"1f3cf3d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entendemos la importancia del bienestar en la educaci\u00f3n. Desde 2019, promovemos su aprendizaje con iniciativas como Global Be Well Day. Priorizamos el bienestar f\u00edsico y mental para que los estudiantes lo gestionen ahora y en el futuro.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63a6b72e e-con-full e-flex e-con e-child\" data-id=\"63a6b72e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ff3c742 elementor-widget elementor-widget-image\" data-id=\"7ff3c742\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/12\/Niveles-Academicos_Gimnasio-del-Norte-3.png?w=1000\" title=\"Niveles Acade\u0301micos_Gimnasio del Norte\" alt=\"Niveles Acade\u0301micos_Gimnasio del Norte\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b4cba5 elementor-widget elementor-widget-heading\" data-id=\"9b4cba5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aprendizaje digital<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56f2fbb4 elementor-widget elementor-widget-text-editor\" data-id=\"56f2fbb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex max-w-full flex-col flex-grow\"><div class=\"min-h-8 text-message flex w-full flex-col items-end gap-2 whitespace-normal break-words text-start [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"cc024abd-d0ae-45b1-925d-a1cd002eddf4\" data-message-model-slug=\"gpt-4o\"><div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\"><div class=\"markdown prose w-full break-words dark:prose-invert dark\"><p>En Cognita preparamos a nuestros estudiantes para un mundo digital, formando ciudadanos responsables, aprendices que aprovechan la tecnolog\u00eda, comunicadores que colaboran e innovadores que transforman con nuevas tecnolog\u00edas.<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-26ab16a e-con-full e-flex e-con e-child\" data-id=\"26ab16a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-c7768a3 e-con-full e-flex e-con e-child\" data-id=\"c7768a3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b4bcd8a elementor-widget elementor-widget-image\" data-id=\"b4bcd8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/12\/Niveles-Academicos_Gimnasio-del-Norte-2.png?w=1080\" title=\"Niveles Acade\u0301micos_Gimnasio del Norte\" alt=\"Niveles Acade\u0301micos_Gimnasio del Norte\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03c09ee elementor-widget elementor-widget-heading\" data-id=\"03c09ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Oportunidades de enriquecimiento<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8895f27 elementor-widget elementor-widget-text-editor\" data-id=\"8895f27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La educaci\u00f3n en Cognita va m\u00e1s all\u00e1 del aula, fomentando adaptabilidad, autonom\u00eda y actitud positiva para el \u00e9xito. Nuestros educadores brindan experiencias de aprendizaje diversas, desarrollando habilidades para la vida y creando recuerdos significativos<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d3f788b e-con-full e-flex e-con e-child\" data-id=\"d3f788b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0b293aa elementor-widget elementor-widget-image\" data-id=\"0b293aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/12\/Niveles-Academicos_Gimnasio-del-Norte-4.png?w=1000\" title=\"Niveles Acade\u0301micos_Gimnasio del Norte\" alt=\"Ni\u00f1o sonriendo en zonas de juegos\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4c3aa7 elementor-widget elementor-widget-heading\" data-id=\"e4c3aa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Acci\u00f3n global y social<br><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8398e8 elementor-widget elementor-widget-text-editor\" data-id=\"a8398e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nuestros estudiantes son parte de comunidades locales y globales. Fomentamos la empat\u00eda y el impacto positivo a trav\u00e9s del aprendizaje-servicio, voluntariado y proyectos comunitarios, ense\u00f1\u00e1ndoles toma de decisiones \u00e9ticas, respeto por la diversidad y pr\u00e1cticas sostenibles<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d6f60e1 e-flex e-con-boxed e-con e-parent\" data-id=\"6d6f60e1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-440e7555 e-flex e-con-boxed e-con e-child\" data-id=\"440e7555\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6217f549 e-flex e-con-boxed e-con e-child\" data-id=\"6217f549\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e7424df elementor-widget elementor-widget-heading\" data-id=\"5e7424df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Enlaces de inter\u00e9s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-785b8792 e-con-full e-flex e-con e-child\" data-id=\"785b8792\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32b48764 elementor-align-left elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"32b48764\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/gimnorte.edu.co\/es\/admisiones\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user-friends\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M192 256c61.9 0 112-50.1 112-112S253.9 32 192 32 80 82.1 80 144s50.1 112 112 112zm76.8 32h-8.3c-20.8 10-43.9 16-68.5 16s-47.6-6-68.5-16h-8.3C51.6 288 0 339.6 0 403.2V432c0 26.5 21.5 48 48 48h288c26.5 0 48-21.5 48-48v-28.8c0-63.6-51.6-115.2-115.2-115.2zM480 256c53 0 96-43 96-96s-43-96-96-96-96 43-96 96 43 96 96 96zm48 32h-3.8c-13.9 4.8-28.6 8-44.2 8s-30.3-3.2-44.2-8H432c-20.4 0-39.2 5.9-55.7 15.4 24.4 26.3 39.7 61.2 39.7 99.8v38.4c0 2.2-.5 4.3-.6 6.4H592c26.5 0 48-21.5 48-48 0-61.9-50.1-112-112-112z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Admisiones<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13105d33 elementor-align-left elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"13105d33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/gimnorte.edu.co\/es\/enfoque-y-acreditaciones-internacionales\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marked-alt\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 0c-69.59 0-126 56.41-126 126 0 56.26 82.35 158.8 113.9 196.02 6.39 7.54 17.82 7.54 24.2 0C331.65 284.8 414 182.26 414 126 414 56.41 357.59 0 288 0zm0 168c-23.2 0-42-18.8-42-42s18.8-42 42-42 42 18.8 42 42-18.8 42-42 42zM20.12 215.95A32.006 32.006 0 0 0 0 245.66v250.32c0 11.32 11.43 19.06 21.94 14.86L160 448V214.92c-8.84-15.98-16.07-31.54-21.25-46.42L20.12 215.95zM288 359.67c-14.07 0-27.38-6.18-36.51-16.96-19.66-23.2-40.57-49.62-59.49-76.72v182l192 64V266c-18.92 27.09-39.82 53.52-59.49 76.72-9.13 10.77-22.44 16.95-36.51 16.95zm266.06-198.51L416 224v288l139.88-55.95A31.996 31.996 0 0 0 576 426.34V176.02c0-11.32-11.43-19.06-21.94-14.86z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Curr\u00edculos Internacionales <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17e8c26f elementor-align-left elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"17e8c26f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/gimnorte.edu.co\/es\/bienestar\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-award\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M97.12 362.63c-8.69-8.69-4.16-6.24-25.12-11.85-9.51-2.55-17.87-7.45-25.43-13.32L1.2 448.7c-4.39 10.77 3.81 22.47 15.43 22.03l52.69-2.01L105.56 507c8 8.44 22.04 5.81 26.43-4.96l52.05-127.62c-10.84 6.04-22.87 9.58-35.31 9.58-19.5 0-37.82-7.59-51.61-21.37zM382.8 448.7l-45.37-111.24c-7.56 5.88-15.92 10.77-25.43 13.32-21.07 5.64-16.45 3.18-25.12 11.85-13.79 13.78-32.12 21.37-51.62 21.37-12.44 0-24.47-3.55-35.31-9.58L252 502.04c4.39 10.77 18.44 13.4 26.43 4.96l36.25-38.28 52.69 2.01c11.62.44 19.82-11.27 15.43-22.03zM263 340c15.28-15.55 17.03-14.21 38.79-20.14 13.89-3.79 24.75-14.84 28.47-28.98 7.48-28.4 5.54-24.97 25.95-45.75 10.17-10.35 14.14-25.44 10.42-39.58-7.47-28.38-7.48-24.42 0-52.83 3.72-14.14-.25-29.23-10.42-39.58-20.41-20.78-18.47-17.36-25.95-45.75-3.72-14.14-14.58-25.19-28.47-28.98-27.88-7.61-24.52-5.62-44.95-26.41-10.17-10.35-25-14.4-38.89-10.61-27.87 7.6-23.98 7.61-51.9 0-13.89-3.79-28.72.25-38.89 10.61-20.41 20.78-17.05 18.8-44.94 26.41-13.89 3.79-24.75 14.84-28.47 28.98-7.47 28.39-5.54 24.97-25.95 45.75-10.17 10.35-14.15 25.44-10.42 39.58 7.47 28.36 7.48 24.4 0 52.82-3.72 14.14.25 29.23 10.42 39.59 20.41 20.78 18.47 17.35 25.95 45.75 3.72 14.14 14.58 25.19 28.47 28.98C104.6 325.96 106.27 325 121 340c13.23 13.47 33.84 15.88 49.74 5.82a39.676 39.676 0 0 1 42.53 0c15.89 10.06 36.5 7.65 49.73-5.82zM97.66 175.96c0-53.03 42.24-96.02 94.34-96.02s94.34 42.99 94.34 96.02-42.24 96.02-94.34 96.02-94.34-42.99-94.34-96.02z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\"> Bienestar<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Somos Redcol Creemos en el poder transformador de la educaci\u00f3n. En nuestra red de colegios, cada estudiante es \u00fanico, y ofrecemos un servicio de excelencia que respeta, inspira y potencia [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-2034","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Familia Cognita - Redcol - Gimnasio del Norte | Colegios Redcol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Familia Cognita - Redcol - Gimnasio del Norte | Colegios Redcol\" \/>\n<meta property=\"og:description\" content=\"Somos Redcol Creemos en el poder transformador de la educaci\u00f3n. En nuestra red de colegios, cada estudiante es \u00fanico, y ofrecemos un servicio de excelencia que respeta, inspira y potencia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimnasio del Norte | Colegios Redcol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gimnasiodelnorte.valledupar\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-01T03:17:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/12\/Banner_FAMILIA-COGNITA-REDCOL_Gimnasio-del-Norte.jpg?w=1440\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/\",\"url\":\"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/\",\"name\":\"Familia Cognita - Redcol - Gimnasio del Norte | Colegios Redcol\",\"isPartOf\":{\"@id\":\"https:\/\/gimnorte.edu.co\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/12\/Banner_FAMILIA-COGNITA-REDCOL_Gimnasio-del-Norte.jpg?w=1440\",\"datePublished\":\"2024-04-29T13:01:25+00:00\",\"dateModified\":\"2025-02-01T03:17:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/#primaryimage\",\"url\":\"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/12\/Banner_FAMILIA-COGNITA-REDCOL_Gimnasio-del-Norte.jpg?w=1440\",\"contentUrl\":\"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/12\/Banner_FAMILIA-COGNITA-REDCOL_Gimnasio-del-Norte.jpg?w=1440\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/gimnorte.edu.co\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Familia Cognita &#8211; Redcol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gimnorte.edu.co\/es\/#website\",\"url\":\"https:\/\/gimnorte.edu.co\/es\/\",\"name\":\"Gimnasio del Norte | Colegios Redcol\",\"description\":\"El Gimnasio del Norte es un colegio de excelencia acad\u00e9mica, abr\u00edmos las  puertas de nuestra Casa Grande para estudiantes desde los 12 meses de edad.\",\"publisher\":{\"@id\":\"https:\/\/gimnorte.edu.co\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gimnorte.edu.co\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/gimnorte.edu.co\/es\/#organization\",\"name\":\"Gimnasio del Norte | Colegios Redcol\",\"url\":\"https:\/\/gimnorte.edu.co\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/gimnorte.edu.co\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/11\/Logo_Gimnasio_del_Norte.png\",\"contentUrl\":\"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/11\/Logo_Gimnasio_del_Norte.png\",\"width\":808,\"height\":389,\"caption\":\"Gimnasio del Norte | Colegios Redcol\"},\"image\":{\"@id\":\"https:\/\/gimnorte.edu.co\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/gimnasiodelnorte.valledupar\/\",\"https:\/\/www.instagram.com\/gimnortevup\/\",\"https:\/\/www.youtube.com\/user\/ZONANORTETVGIMNORTE\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Familia Cognita - Redcol - Gimnasio del Norte | Colegios Redcol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/","og_locale":"es_ES","og_type":"article","og_title":"Familia Cognita - Redcol - Gimnasio del Norte | Colegios Redcol","og_description":"Somos Redcol Creemos en el poder transformador de la educaci\u00f3n. En nuestra red de colegios, cada estudiante es \u00fanico, y ofrecemos un servicio de excelencia que respeta, inspira y potencia [&hellip;]","og_url":"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/","og_site_name":"Gimnasio del Norte | Colegios Redcol","article_publisher":"https:\/\/www.facebook.com\/gimnasiodelnorte.valledupar\/","article_modified_time":"2025-02-01T03:17:32+00:00","og_image":[{"url":"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/12\/Banner_FAMILIA-COGNITA-REDCOL_Gimnasio-del-Norte.jpg?w=1440","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/","url":"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/","name":"Familia Cognita - Redcol - Gimnasio del Norte | Colegios Redcol","isPartOf":{"@id":"https:\/\/gimnorte.edu.co\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/#primaryimage"},"image":{"@id":"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/12\/Banner_FAMILIA-COGNITA-REDCOL_Gimnasio-del-Norte.jpg?w=1440","datePublished":"2024-04-29T13:01:25+00:00","dateModified":"2025-02-01T03:17:32+00:00","breadcrumb":{"@id":"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/#primaryimage","url":"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/12\/Banner_FAMILIA-COGNITA-REDCOL_Gimnasio-del-Norte.jpg?w=1440","contentUrl":"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/12\/Banner_FAMILIA-COGNITA-REDCOL_Gimnasio-del-Norte.jpg?w=1440"},{"@type":"BreadcrumbList","@id":"https:\/\/gimnorte.edu.co\/es\/familia-cognita-redcol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gimnorte.edu.co\/es\/"},{"@type":"ListItem","position":2,"name":"Familia Cognita &#8211; Redcol"}]},{"@type":"WebSite","@id":"https:\/\/gimnorte.edu.co\/es\/#website","url":"https:\/\/gimnorte.edu.co\/es\/","name":"Gimnasio del Norte | Colegios Redcol","description":"El Gimnasio del Norte es un colegio de excelencia acad\u00e9mica, abr\u00edmos las  puertas de nuestra Casa Grande para estudiantes desde los 12 meses de edad.","publisher":{"@id":"https:\/\/gimnorte.edu.co\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnorte.edu.co\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnorte.edu.co\/es\/#organization","name":"Gimnasio del Norte | Colegios Redcol","url":"https:\/\/gimnorte.edu.co\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnorte.edu.co\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/11\/Logo_Gimnasio_del_Norte.png","contentUrl":"https:\/\/gimnorte.edu.co\/wp-content\/uploads\/sites\/29\/2024\/11\/Logo_Gimnasio_del_Norte.png","width":808,"height":389,"caption":"Gimnasio del Norte | Colegios Redcol"},"image":{"@id":"https:\/\/gimnorte.edu.co\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gimnasiodelnorte.valledupar\/","https:\/\/www.instagram.com\/gimnortevup\/","https:\/\/www.youtube.com\/user\/ZONANORTETVGIMNORTE"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/gimnorte.edu.co\/es\/wp-json\/wp\/v2\/pages\/2034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnorte.edu.co\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gimnorte.edu.co\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gimnorte.edu.co\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnorte.edu.co\/es\/wp-json\/wp\/v2\/comments?post=2034"}],"version-history":[{"count":20,"href":"https:\/\/gimnorte.edu.co\/es\/wp-json\/wp\/v2\/pages\/2034\/revisions"}],"predecessor-version":[{"id":132510,"href":"https:\/\/gimnorte.edu.co\/es\/wp-json\/wp\/v2\/pages\/2034\/revisions\/132510"}],"wp:attachment":[{"href":"https:\/\/gimnorte.edu.co\/es\/wp-json\/wp\/v2\/media?parent=2034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}